{"id":19580,"date":"2020-09-14T09:12:59","date_gmt":"2020-09-14T07:12:59","guid":{"rendered":"https:\/\/edorteam.com\/privacidad\/"},"modified":"2026-01-29T12:34:56","modified_gmt":"2026-01-29T11:34:56","slug":"privacidad","status":"publish","type":"page","link":"https:\/\/edorteam.com\/en\/privacidad\/","title":{"rendered":"Pol\u00edtica de privacidad"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; custom_padding_last_edited=&#8221;off|desktop&#8221; _builder_version=&#8221;4.27.5&#8243; _module_preset=&#8221;default&#8221; background_color=&#8221;#F8F8F8&#8243; use_background_color_gradient=&#8221;on&#8221; background_color_gradient_direction=&#8221;280deg&#8221; background_color_gradient_stops=&#8221;rgba(0,0,0,0) 20%|#f8f8f8 80%&#8221; background_color_gradient_overlays_image=&#8221;on&#8221; background_color_gradient_start=&#8221;rgba(0,0,0,0)&#8221; background_color_gradient_start_position=&#8221;20%&#8221; background_color_gradient_end=&#8221;#e5e5e5&#8243; background_color_gradient_end_position=&#8221;80%&#8221; background_image=&#8221;https:\/\/edorteam.com\/wp-content\/uploads\/ciber-seguridad-lleida-informatica.jpg&#8221; background_position=&#8221;center_right&#8221; custom_padding=&#8221;120px||||false|false&#8221; custom_padding_tablet=&#8221;100px||||false|false&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;top&#8221; hover_enabled=&#8221;0&#8243; background_last_edited=&#8221;on|phone&#8221; background_size_tablet=&#8221;initial&#8221; background_position_tablet=&#8221;bottom_center&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_row _builder_version=&#8221;4.16&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;4.16&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; theme_builder_area=&#8221;post_content&#8221;][et_pb_text _builder_version=&#8221;4.27.5&#8243; hover_enabled=&#8221;0&#8243; global_colors_info=&#8221;{}&#8221; theme_builder_area=&#8221;post_content&#8221; sticky_enabled=&#8221;0&#8243;]<\/p>\n<p>EDOR TEAM SOFT, S.L. se compromete a proteger la privacidad de los usuarios que accedan a esta web y\/o cualquiera de sus servicios. La utilizaci\u00f3n de la web y\/o cualquiera de los servicios ofrecidos por EDOR TEAM SOFT, S.L., implica la aceptaci\u00f3n por parte del usuario de las disposiciones contenidas en la presente Pol\u00edtica de Privacidad y que sus datos personales sean tratados seg\u00fan se estipula. Por favor, tenga en cuenta que, aunque pueda haber enlaces de nuestra web a otras webs, esta Pol\u00edtica de Privacidad no se aplica a otras compa\u00f1\u00edas u organizaciones a las que la web est\u00e9 redirigida. EDOR TEAM SOFT, S.L. no controla el contenido de las webs de terceros ni acepta ning\u00fan tipo de responsabilidad por el contenido o las pol\u00edticas de privacidad de estos sitios web.<\/p>\n<p><strong>1) INFORMACI\u00d3N DEL TITULAR<\/strong><\/p>\n<p>En cumplimiento del art\u00edculo 10 de la Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y Comercio Electr\u00f3nico, a continuaci\u00f3n, se exponen los datos identificativos del Titular:<\/p>\n<table width=\"567\">\n<tbody>\n<tr>\n<td width=\"133\">Web:<\/td>\n<td width=\"433\">https:\/\/edorteam.com\/<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">Titular:<\/td>\n<td width=\"433\">EDOR TEAM SOFT, S.L.<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">Domicilio:<\/td>\n<td width=\"433\">CALLE ISABEL COLBRAND, 6 &#8211; 5 PLT. 28050-MADRID<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">C.I.F.:<\/td>\n<td width=\"433\">B25286014<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">Tel\u00e9fono:<\/td>\n<td width=\"433\">973248601<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">Correo electr\u00f3nico:<\/td>\n<td width=\"433\">info@edorteam.com<\/td>\n<\/tr>\n<tr>\n<td width=\"133\">Datos registrales:<\/td>\n<td width=\"433\">Registre Mercantil de Lleida. Tomo 183, Folio 10, Hoja L3379<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n<p>&nbsp;<\/p>\n<p><strong>2) LEYES APLICABLES<\/strong><\/p>\n<p>La presente pol\u00edtica de privacidad se apoya para su confecci\u00f3n en base a la normativa espa\u00f1ola y europea vigente en materia de protecci\u00f3n de datos personales en internet. En concreto, la misma respeta las siguientes normas:<\/p>\n<p>&#8211; El Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, relativo a la protecci\u00f3n de las personas f\u00edsicas en lo que respecta al tratamiento de datos personales y a la libre circulaci\u00f3n de estos datos (RGPD).<\/p>\n<p>&#8211; La Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales (LOPD-GDD).<\/p>\n<p>&#8211; La Ley 34\/2002, de 11 de julio, de Servicios de la Sociedad de la Informaci\u00f3n y de Comercio Electr\u00f3nico (LSSI-CE).<\/p>\n<p><strong>3) CUESTIONES SOBRE PRIVACIDAD<\/strong><\/p>\n<p>En cumplimiento del Reglamento (UE) 2016\/679 del Parlamento Europeo y del Consejo, de 27 de abril de 2016, (RGPD) y de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de derechos digitales, le ofrecemos la siguiente informaci\u00f3n sobre el tratamiento de los datos personales que usted pueda facilitarnos:<\/p>\n<p><strong>Responsable del Fichero<\/strong><\/p>\n<p>EDOR TEAM SOFT, S.L.<\/p>\n<p>Nuestros datos se encuentran en la parte superior de este aviso legal.<\/p>\n<p><strong>Registro de Datos de Car\u00e1cter Personal<\/strong><\/p>\n<p>En cumplimiento de lo establecido en el RGPD y la LOPD-GDD, le informamos que los datos personales recabados por EDOR TEAM SOFT, S.L., mediante los formularios extendidos en sus p\u00e1ginas quedar\u00e1n incorporados y ser\u00e1n tratados en nuestro fichero con el fin de poder facilitar, agilizar y cumplir los compromisos establecidos entre EDOR TEAM SOFT, S.L. y el Usuario o el mantenimiento de la relaci\u00f3n que se establezca en los formularios que este rellene, o para atender una solicitud o consulta del mismo. Asimismo, de conformidad con lo previsto en el RGPD y la LOPD-GDD, salvo que sea de aplicaci\u00f3n la excepci\u00f3n prevista en el art\u00edculo 30.5 del RGPD, se mantiene un registro de actividades de tratamiento que especifica, seg\u00fan sus finalidades, las actividades de tratamiento llevadas a cabo y las dem\u00e1s circunstancias establecidas en el RGPD.<\/p>\n<p><strong>Base Legal para el tratamiento<\/strong><\/p>\n<p>La base legal para el tratamiento de los datos personales es el consentimiento. EDOR TEAM SOFT, S.L. se compromete a recabar el consentimiento expreso y verificable del Usuario para el tratamiento de sus datos personales para uno o varios fines espec\u00edficos.<\/p>\n<p>El Usuario tendr\u00e1 derecho a retirar su consentimiento en cualquier momento. Ser\u00e1 tan f\u00e1cil retirar el consentimiento como darlo. Como regla general, la retirada del consentimiento no condicionar\u00e1 el uso del Sitio Web.<\/p>\n<p>En las ocasiones en las que el Usuario deba o pueda facilitar sus datos a trav\u00e9s de formularios para realizar consultas, solicitar informaci\u00f3n o por motivos relacionados con el contenido del Sitio Web, se le informar\u00e1 en caso de que la cumplimentaci\u00f3n de alguno de ellos sea obligatoria debido a que los mismos sean imprescindibles para el correcto desarrollo de la operaci\u00f3n realizada.<\/p>\n<p>Otras bases de Legitimaci\u00f3n:<\/p>\n<p>Cumplimiento de obligaciones legales.<\/p>\n<p>Inter\u00e9s leg\u00edtimo: env\u00edo de publicidad propia.<\/p>\n<p><strong>Categor\u00edas de datos<\/strong><\/p>\n<p>Las categor\u00edas de datos que se tratan en EDOR TEAM SOFT, S.L. son \u00fanicamente datos identificativos. En ning\u00fan caso, se tratan categor\u00edas especiales de datos personales en el sentido del art\u00edculo 9 del RGPD.<\/p>\n<p><strong>Procedencia de sus datos<\/strong><\/p>\n<p><strong>Periodo de Conservaci\u00f3n de los datos personales<\/strong><\/p>\n<p>Los datos personales solo ser\u00e1n retenidos durante el tiempo m\u00ednimo necesario para los fines de su tratamiento y, en todo caso, \u00fanicamente durante el siguiente plazo: Los datos se conservar\u00e1n mientras el usuario sea cliente de nuestro servicios, o previo consentimiento desee que le enviemos informaci\u00f3n sobre nuestros servicios y productos., o hasta que el Usuario solicite su derecho de cancelaci\u00f3n u oposici\u00f3n, o limitaci\u00f3n al tratamiento. Sin embargo, conservaremos determinados datos personales identificativos y del tr\u00e1fico durante el plazo m\u00e1ximo de 2 a\u00f1os para el caso de que fuera requerido por los Jueces y Tribunales o para incoar acciones internas derivadas del uso indebido de la p\u00e1gina web.<\/p>\n<p>En el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca del plazo durante el cual se conservar\u00e1n los datos personales o, cuando eso no sea posible, los criterios utilizados para determinar este plazo.<\/p>\n<p>Asimismo, le informamos que nuestras pol\u00edticas de conservaci\u00f3n de la informaci\u00f3n se ajustan a los plazos que marcan las distintas responsabilidades legales a efectos de prescripci\u00f3n:<\/p>\n<ol>\n<li>a) Regla General:<\/li>\n<\/ol>\n<p>En virtud de lo establecido en el art\u00edculo 30 del C\u00f3digo de Comercio, y salvo otros criterios, todos los documentos y\/o informaci\u00f3n de la empresa se conservar\u00e1 durante 6 a\u00f1os.<\/p>\n<p>Esto afecta a toda la documentaci\u00f3n contable, fiscal, laboral o mercantil, incluida la correspondencia.<\/p>\n<ol>\n<li>b) Plazos espec\u00edficos:<\/li>\n<\/ol>\n<p>Nuestra empresa tambi\u00e9n debe marcar unos m\u00ednimos plazos en funci\u00f3n de la tipolog\u00eda de datos que se trate y atendiendo a los distintos plazos de prescripci\u00f3n, que deber\u00e1n conocer cada uno de los departamentos.<\/p>\n<p>No ser\u00e1 objeto de decisiones basadas en tratamientos automatizados que produzcan efectos sobre sus datos.<\/p>\n<p><strong>Fines del tratamiento<\/strong><\/p>\n<p>Detallamos a continuaci\u00f3n las finalidades de los tratamientos de datos llevados a cabo:<\/p>\n<p>GESTION DE CLIENTES: Poder prestar los servicios contratados dentro de actividad natural de cada empresa y facturar los mismos. Los datos proporcionados se conservar\u00e1n mientras se mantenga la relaci\u00f3n comercial o durante los a\u00f1os necesarios para cumplir con las obligaciones legales.<\/p>\n<p>GESTION DE PRESUPUESTOS: Poder enviar a posibles clientes presupuestos de servicios y\/o productos. Los datos proporcionados se conservar\u00e1n mientras no solicite el cese de dicho tratamiento.<\/p>\n<p>GESTION DE POSIBLES CLIENTES: Poder enviar a personas con inter\u00e9s leg\u00edtimo informaci\u00f3n relacionada con nuestros productos y servicios por cualquier medio disponible, e invitarles a eventos de su inter\u00e9s. Los datos proporcionados se conservar\u00e1n mientras no solicite el cese de dicho tratamiento y ser\u00e1n recabados previo consentimiento expreso.<\/p>\n<p>SELECCI\u00d3N DE PERSONAL: Poder gestionar todos aquellos curr\u00edculum y otras informaciones aportadas por candidatos a un puesto de trabajo y el de mantenerles informados de las distintas vacantes a un puesto de trabajo que se produzcan en nuestra organizaci\u00f3n y\/o clientes que contratan el servicio de selecci\u00f3n de personal. Los datos proporcionados se conservar\u00e1n hasta la adjudicaci\u00f3n de un puesto de trabajo o hasta que se ejerza el derecho de cancelaci\u00f3n sobre dicho tratamiento (dicho plazo no superar\u00e1 un a\u00f1o). En todo momento el candidato puede oponerse o limitar el alcance del tratamiento de sus datos.<\/p>\n<p>RELACIONES CON PROVEEDORES: Poder realizar pedidos y pago de los servicios. Los datos proporcionados se conservar\u00e1n mientras se mantenga la relaci\u00f3n comercial o durante los a\u00f1os necesarios para cumplir con las obligaciones legales.<\/p>\n<p>ORGANIZACI\u00d3N DE EVENTOS: Poder organizar eventos (cursos, charlas, concursos y otras actividades de difusi\u00f3n) por parte de cualquiera de los Responsables del Tratamiento. Los datos proporcionados se conservar\u00e1n mientras no solicite el cese de la actividad o durante los a\u00f1os necesarios para la justificaci\u00f3n de la actividad.<\/p>\n<p>MAILING DE OFERTAS: Si usted es cliente del Responsable del tratamiento y tiene aplicada la pol\u00edtica de ofertas, recibir\u00e1 peri\u00f3dicamente al inicio de cada promoci\u00f3n un email publicitario indic\u00e1ndole cu\u00e1les ser\u00e1n los productos ofertados y sus precios, adem\u00e1s de un enlace en el que podr\u00e1 descargarse las mismas para promocionarlo usted mismo si lo desea.<\/p>\n<p><strong>Destinatarios de los datos<\/strong><\/p>\n<p>Los datos personales del Usuario no ser\u00e1n compartidos con terceros.<\/p>\n<p>En cualquier caso, en el momento en que se obtengan los datos personales, se informar\u00e1 al Usuario acerca de los destinatarios o las categor\u00edas de destinatarios de los datos personales.<\/p>\n<p><strong>Datos personales de menores<\/strong><\/p>\n<p>Respetando lo establecido en los art\u00edculos 8 del RGPD y 7 de la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales, solo los mayores de 14 a\u00f1os podr\u00e1n otorgar su consentimiento para el tratamiento de sus datos personales de forma l\u00edcita por EDOR TEAM SOFT, S.L.. Si se trata de un menor de 14 a\u00f1os, ser\u00e1 necesario el consentimiento de los padres o tutores para el tratamiento, y este solo se considerar\u00e1 l\u00edcito en la medida en la que los mismos lo hayan autorizado. De no ser as\u00ed el\/la representante legal deber\u00e1 inform\u00e1oslo en cuanto sea posible.<\/p>\n<p><strong>Derechos derivados del tratamiento de datos personales<\/strong><\/p>\n<p>El Usuario podr\u00e1 ejercer frente al Responsable del tratamiento los siguientes derechos reconocidos en el RGPD y la Ley Org\u00e1nica 3\/2018, de 5 de diciembre, de Protecci\u00f3n de Datos Personales y garant\u00eda de los derechos digitales:<\/p>\n<p>Derecho de acceso: Es el derecho del Usuario a obtener confirmaci\u00f3n de si EDOR TEAM SOFT, S.L. est\u00e1 tratando o no sus datos personales y, en caso afirmativo, obtener informaci\u00f3n sobre sus datos concretos de car\u00e1cter personal y del tratamiento que EDOR TEAM SOFT, S.L. haya realizado o realice, as\u00ed como, entre otra, de la informaci\u00f3n disponible sobre el origen de dichos datos y los destinatarios de las comunicaciones realizadas o previstas de los mismos.<\/p>\n<p>Derecho de rectificaci\u00f3n: Es el derecho del Usuario a que se modifiquen sus datos personales que resulten ser inexactos o, teniendo en cuenta los fines del tratamiento, incompletos.<\/p>\n<p>Derecho de supresi\u00f3n (&#8220;el derecho al olvido&#8221;): Es el derecho del Usuario, siempre que la legislaci\u00f3n vigente no establezca lo contrario, a obtener la supresi\u00f3n de sus datos personales cuando estos ya no sean necesarios para los fines para los cuales fueron recogidos o tratados; el Usuario haya retirado su consentimiento al tratamiento y este no cuente con otra base legal; el Usuario se oponga al tratamiento y no exista otro motivo leg\u00edtimo para continuar con el mismo; los datos personales hayan sido tratados de manera il\u00edcita; los datos personales deban suprimirse en cumplimiento de una obligaci\u00f3n legal; o los datos personales hayan sido obtenidos producto de una oferta directa de servicios de la sociedad de la informaci\u00f3n a un menor de 14 a\u00f1os. Adem\u00e1s de suprimir los datos, el Responsable del tratamiento, teniendo en cuenta la tecnolog\u00eda disponible y el coste de su aplicaci\u00f3n, deber\u00e1 adoptar medidas razonables para informar a los responsables que est\u00e9n tratando los datos personales de la solicitud del interesado de supresi\u00f3n de cualquier enlace a esos datos personales.<\/p>\n<p>Derecho a la limitaci\u00f3n del tratamiento: Es el derecho del Usuario a limitar el tratamiento de sus datos personales. El Usuario tiene derecho a obtener la limitaci\u00f3n del tratamiento cuando impugne la exactitud de sus datos personales; el tratamiento sea il\u00edcito; el Responsable del tratamiento ya no necesite los datos personales, pero el Usuario lo necesite para hacer reclamaciones; y cuando el Usuario se haya opuesto al tratamiento.<\/p>\n<p>Derecho a la portabilidad de los datos: En caso de que el tratamiento se efect\u00fae por medios automatizados, el Usuario tendr\u00e1 derecho a recibir del Responsable del tratamiento sus datos personales en un formato estructurado, de uso com\u00fan y lectura mec\u00e1nica, y a transmitirlos a otro responsable del tratamiento. Siempre que sea t\u00e9cnicamente posible, el Responsable del tratamiento transmitir\u00e1 directamente los datos a ese otro responsable.<\/p>\n<p>Derecho de oposici\u00f3n: Es el derecho del Usuario a que no se lleve a cabo el tratamiento de sus datos de car\u00e1cter personal o se cese el tratamiento de los mismos por parte de EDOR TEAM SOFT, S.L..<\/p>\n<p>Derecho a no ser objeto de una decisi\u00f3n basada \u00fanicamente en el tratamiento automatizado, incluida la elaboraci\u00f3n de perfiles: Es el derecho del Usuario a no ser objeto de una decisi\u00f3n individualizada basada \u00fanicamente en el tratamiento automatizado de sus datos personales, incluida la elaboraci\u00f3n de perfiles, existente salvo que la legislaci\u00f3n vigente establezca lo contrario.<\/p>\n<p>Finalmente, los\/las interesados\/as tienen derecho a presentar una reclamaci\u00f3n ante la Autoridad de Control competente (AEPD) en caso de que el Usuario considere que existe un problema o infracci\u00f3n de la normativa vigente en la forma en la que se est\u00e1n tratando sus datos personales.<\/p>\n<p>Puede ejercer los derechos anteriores envi\u00e1ndonos un escrito adjuntando una copia de un documento que lo identifique a nuestro domicilio o correo electr\u00f3nico (que aparecen al principio del presente texto).<\/p>\n<p><strong>4) PRINCIPIOS APLICABLES AL TRATAMIENTO DE DATOS PERSONALES<\/strong><\/p>\n<p>El tratamiento de los datos personales del cliente usuario se someter\u00e1 a los siguientes principios recogidos en el art. 5 del RGPD y en el art\u00edculo 4 y siguientes de la LOPDGDD:<\/p>\n<p><strong>Principio de licitud, lealtad y transparencia:<\/strong><\/p>\n<p>Se requerir\u00e1 en todo momento el consentimiento del usuario previa informaci\u00f3n completamente transparente de los fines para los cuales se recogen los datos personales.<\/p>\n<p><strong>Principio de limitaci\u00f3n de la finalidad:<\/strong><\/p>\n<p>Los datos personales ser\u00e1n recogidos con fines determinados, expl\u00edcitos y leg\u00edtimos.<\/p>\n<p><strong>Principio de minimizaci\u00f3n de datos:<\/strong><\/p>\n<p>Los datos personales recogidos ser\u00e1n \u00fanicamente los estrictamente necesarios en relaci\u00f3n con los fines para los que son tratados.<\/p>\n<p><strong>Principio de exactitud:<\/strong><\/p>\n<p>Los datos personales deben ser exactos y estar siempre actualizados.<\/p>\n<p><strong>Principio de limitaci\u00f3n del plazo de conservaci\u00f3n:<\/strong><\/p>\n<p>Los datos personales solo ser\u00e1n mantenidos de forma que se permita la identificaci\u00f3n del usuario durante el tiempo necesario para los fines del tratamiento.<\/p>\n<p><strong>Principio de integridad y confidencialidad:<\/strong><\/p>\n<p>Los datos personales ser\u00e1n tratados de manera que se garantice su seguridad y reserva.<\/p>\n<p><strong>Principio de responsabilidad proactiva:<\/strong><\/p>\n<p>El responsable del Sitio Web mantendr\u00e1 y regular\u00e1 los medios t\u00e9cnicos y log\u00edsticos necesarios suficientes para que todos los principios aplicables al tratamiento se cumplan.<\/p>\n<p><strong>5) \u00bfQU\u00c9 MEDIDAS DE SEGURIDAD APLICAMOS?<\/strong><\/p>\n<p>Aplicamos las medidas de seguridad establecidas en el art\u00edculo 32 del RGPD, por lo tanto, hemos adoptado las medidas de seguridad necesarias para garantizar un nivel de seguridad adecuado al riesgo del tratamiento de los datos que realizamos, con mecanismos que nos permiten garantizar la confidencialidad, integridad, disponibilidad y resiliencia permanente de los sistemas y servicios de tratamiento.<\/p>\n<p>Algunas de estas medidas son:<\/p>\n<p>&#8211; Informaci\u00f3n de las pol\u00edticas de tratamiento de los datos al personal.<\/p>\n<p>&#8211; Realizaci\u00f3n de copias de seguridad peri\u00f3dicas.<\/p>\n<p>&#8211; Control de acceso a los datos.<\/p>\n<p>&#8211; Procesos de verificaci\u00f3n, evaluaci\u00f3n y valoraci\u00f3n regulares.<\/p>\n<p><strong>6) SECRETO Y SEGURIDAD DE LOS DATOS PERSONALES<\/strong><\/p>\n<p>EDOR TEAM SOFT, S.L. se compromete a adoptar las medidas t\u00e9cnicas y organizativas necesarias, seg\u00fan el nivel de seguridad adecuado al riesgo de los datos recogidos, de forma que se garantice la seguridad de los datos de car\u00e1cter personal y se evite la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p>\n<p>El Sitio Web cuenta con un certificado SSL (Secure Socket Layer), que asegura que los datos personales se transmiten de forma segura y confidencial, al ser la transmisi\u00f3n de los datos entre el servidor y el Usuario, y en retroalimentaci\u00f3n, totalmente cifrada o encriptada.<\/p>\n<p>Sin embargo, debido a que EDOR TEAM SOFT, S.L. no puede garantizar la inexpugnabilidad de internet ni la ausencia total de hackers u otros que accedan de modo fraudulento a los datos personales, el Responsable del tratamiento se compromete a comunicar al Usuario sin dilaci\u00f3n indebida cuando ocurra una violaci\u00f3n de la seguridad de los datos personales que sea probable que entra\u00f1e un alto riesgo para los derechos y libertades de las personas f\u00edsicas. Siguiendo lo establecido en el art\u00edculo 4 del RGPD, se entiende por violaci\u00f3n de la seguridad de los datos personales toda violaci\u00f3n de la seguridad que ocasione la destrucci\u00f3n, p\u00e9rdida o alteraci\u00f3n accidental o il\u00edcita de datos personales transmitidos, conservados o tratados de otra forma, o la comunicaci\u00f3n o acceso no autorizados a dichos datos.<\/p>\n<p>Los datos personales ser\u00e1n tratados como confidenciales por el Responsable del tratamiento, quien se compromete a informar de y a garantizar por medio de una obligaci\u00f3n legal o contractual que dicha confidencialidad sea respetada por sus empleados, asociados, y toda persona a la cual le haga accesible la informaci\u00f3n.<\/p>\n<p><strong>7) ENLACES A SITIOS WEB DE TERCEROS<\/strong><\/p>\n<p>El Sitio Web puede incluir hiperv\u00ednculos o enlaces que permiten acceder a p\u00e1ginas web de terceros distintos de EDOR TEAM SOFT, S.L., y que por tanto no son operados por EDOR TEAM SOFT, S.L.. Los titulares de dichos sitios web dispondr\u00e1n de sus propias pol\u00edticas de protecci\u00f3n de datos, siendo ellos mismos, en cada caso, responsables de sus propios ficheros y de sus propias pr\u00e1cticas de privacidad.<\/p>\n<p><strong>8) ACEPTACI\u00d3N Y CAMBIOS EN ESTA POL\u00cdTICA DE PRIVACIDAD<\/strong><\/p>\n<p>Es necesario que el Usuario haya le\u00eddo y est\u00e9 conforme con las condiciones sobre la protecci\u00f3n de datos de car\u00e1cter personal contenidas en esta Pol\u00edtica de Privacidad, as\u00ed como que acepte el tratamiento de sus datos personales para que el Responsable del tratamiento pueda proceder al mismo en la forma, durante los plazos y para las finalidades indicadas. El uso del Sitio Web implicar\u00e1 la aceptaci\u00f3n de la Pol\u00edtica de Privacidad del mismo.<\/p>\n<p>EDOR TEAM SOFT, S.L. se reserva el derecho a modificar su Pol\u00edtica de Privacidad, de acuerdo a su propio criterio, o motivado por un cambio legislativo, jurisprudencial o doctrinal de la Agencia Espa\u00f1ola de Protecci\u00f3n de Datos. Los cambios o actualizaciones de esta Pol\u00edtica de Privacidad no ser\u00e1n notificados de forma expl\u00edcita al Usuario. Se recomienda al Usuario consultar esta p\u00e1gina de forma peri\u00f3dica para estar al tanto de los \u00faltimos cambios o actualizaciones.<\/p>\n<p>\u00daltima actualizaci\u00f3n: 29\/01\/2026.<\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>EDOR TEAM SOFT, S.L. se compromete a proteger la privacidad de los usuarios que accedan a esta web y\/o cualquiera de sus servicios. La utilizaci\u00f3n de la web y\/o cualquiera de los servicios ofrecidos por EDOR TEAM SOFT, S.L., implica la aceptaci\u00f3n por parte del usuario de las disposiciones contenidas en la presente Pol\u00edtica de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"open","template":"","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"<!-- wp:heading -->\r\n<h2>Who we are<\/h2>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>Our website address is: http:\/\/edorteam.com.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading -->\r\n<h2>What personal data we collect and why we collect it<\/h2>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>Comments<\/h3>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>When visitors leave comments on the site we collect the data shown in the comments form, and also the visitor\u2019s IP address and browser user agent string to help spam detection.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>An anonymized string created from your email address (also called a hash) may be provided to the Gravatar service to see if you are using it. The Gravatar service privacy policy is available here: https:\/\/automattic.com\/privacy\/. After approval of your comment, your profile picture is visible to the public in the context of your comment.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} -->\r\n<h3>Media<\/h3>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>If you upload images to the website, you should avoid uploading images with embedded location data (EXIF GPS) included. Visitors to the website can download and extract any location data from images on the website.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} -->\r\n<h3>Contact forms<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>Cookies<\/h3>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>If you leave a comment on our site you may opt-in to saving your name, email address and website in cookies. These are for your convenience so that you do not have to fill in your details again when you leave another comment. These cookies will last for one year.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>If you visit our login page, we will set a temporary cookie to determine if your browser accepts cookies. This cookie contains no personal data and is discarded when you close your browser.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>When you log in, we will also set up several cookies to save your login information and your screen display choices. Login cookies last for two days, and screen options cookies last for a year. If you select \"Remember Me\", your login will persist for two weeks. If you log out of your account, the login cookies will be removed.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>If you edit or publish an article, an additional cookie will be saved in your browser. This cookie includes no personal data and simply indicates the post ID of the article you just edited. It expires after 1 day.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} -->\r\n<h3>Embedded content from other websites<\/h3>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>Articles on this site may include embedded content (e.g. videos, images, articles, etc.). Embedded content from other websites behaves in the exact same way as if the visitor has visited the other website.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>These websites may collect data about you, use cookies, embed additional third-party tracking, and monitor your interaction with that embedded content, including tracking your interaction with the embedded content if you have an account and are logged in to that website.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading {\"level\":3} -->\r\n<h3>Analytics<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading -->\r\n<h2>Who we share your data with<\/h2>\r\n<!-- \/wp:heading --><!-- wp:heading -->\r\n<h2>How long we retain your data<\/h2>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>If you leave a comment, the comment and its metadata are retained indefinitely. This is so we can recognize and approve any follow-up comments automatically instead of holding them in a moderation queue.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:paragraph -->\r\n<p>For users that register on our website (if any), we also store the personal information they provide in their user profile. All users can see, edit, or delete their personal information at any time (except they cannot change their username). Website administrators can also see and edit that information.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading -->\r\n<h2>What rights you have over your data<\/h2>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>If you have an account on this site, or have left comments, you can request to receive an exported file of the personal data we hold about you, including any data you have provided to us. You can also request that we erase any personal data we hold about you. This does not include any data we are obliged to keep for administrative, legal, or security purposes.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading -->\r\n<h2>Where we send your data<\/h2>\r\n<!-- \/wp:heading --><!-- wp:paragraph -->\r\n<p>Visitor comments may be checked through an automated spam detection service.<\/p>\r\n<!-- \/wp:paragraph --><!-- wp:heading -->\r\n<h2>Your contact information<\/h2>\r\n<!-- \/wp:heading --><!-- wp:heading -->\r\n<h2>Additional information<\/h2>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>How we protect your data<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>What data breach procedures we have in place<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>What third parties we receive data from<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>What automated decision making and\/or profiling we do with user data<\/h3>\r\n<!-- \/wp:heading --><!-- wp:heading {\"level\":3} -->\r\n<h3>Industry regulatory disclosure requirements<\/h3>\r\n<!-- \/wp:heading -->","_et_gb_content_width":"","footnotes":""},"class_list":["post-19580","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Pol\u00edtica de privacidad - Edorteam<\/title>\n<meta name=\"description\" content=\"Pol\u00edtica de privacidad\" \/>\n<meta name=\"robots\" content=\"noindex, nofollow\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Pol\u00edtica de privacidad - Edorteam\" \/>\n<meta property=\"og:description\" content=\"Pol\u00edtica de privacidad\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edorteam.com\/en\/privacidad\/\" \/>\n<meta property=\"og:site_name\" content=\"Edorteam\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/edorteam\/\" \/>\n<meta property=\"article:modified_time\" content=\"2026-01-29T11:34:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edorteam.com\/wp-content\/uploads\/cumplimiento-legal-empresas-abogado.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"598\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:site\" content=\"@edorteam\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/privacidad\\\/\",\"url\":\"https:\\\/\\\/edorteam.com\\\/en\\\/privacidad\\\/\",\"name\":\"Pol\u00edtica de privacidad - Edorteam\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#website\"},\"datePublished\":\"2020-09-14T07:12:59+00:00\",\"dateModified\":\"2026-01-29T11:34:56+00:00\",\"description\":\"Pol\u00edtica de privacidad\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/privacidad\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edorteam.com\\\/en\\\/privacidad\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/privacidad\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edorteam.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Pol\u00edtica de privacidad\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#website\",\"url\":\"https:\\\/\\\/edorteam.com\\\/en\\\/\",\"name\":\"Consultor\u00eda Compliance y protecci\u00f3n de datos\",\"description\":\"Empresa de Ciberseguridad y Protecci\u00f3n de Datos\",\"publisher\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#organization\"},\"alternateName\":\"Edorteam\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edorteam.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#organization\",\"name\":\"Edorteam | Cibersecurity services and data protection company\",\"alternateName\":\"Edorteam\",\"url\":\"https:\\\/\\\/edorteam.com\\\/en\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Edorteam | Cibersecurity services and data protection company\"},\"image\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/en\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/edorteam\\\/\",\"https:\\\/\\\/x.com\\\/edorteam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/edorteam\\\/\",\"https:\\\/\\\/www.instagram.com\\\/edorteam\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Pol\u00edtica de privacidad - Edorteam","description":"Pol\u00edtica de privacidad","robots":{"index":"noindex","follow":"nofollow"},"og_locale":"en_US","og_type":"article","og_title":"Pol\u00edtica de privacidad - Edorteam","og_description":"Pol\u00edtica de privacidad","og_url":"https:\/\/edorteam.com\/en\/privacidad\/","og_site_name":"Edorteam","article_publisher":"https:\/\/www.facebook.com\/edorteam\/","article_modified_time":"2026-01-29T11:34:56+00:00","og_image":[{"width":1000,"height":598,"url":"https:\/\/edorteam.com\/wp-content\/uploads\/cumplimiento-legal-empresas-abogado.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_site":"@edorteam","twitter_misc":{"Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/edorteam.com\/en\/privacidad\/","url":"https:\/\/edorteam.com\/en\/privacidad\/","name":"Pol\u00edtica de privacidad - Edorteam","isPartOf":{"@id":"https:\/\/edorteam.com\/en\/#website"},"datePublished":"2020-09-14T07:12:59+00:00","dateModified":"2026-01-29T11:34:56+00:00","description":"Pol\u00edtica de privacidad","breadcrumb":{"@id":"https:\/\/edorteam.com\/en\/privacidad\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edorteam.com\/en\/privacidad\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/edorteam.com\/en\/privacidad\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edorteam.com\/en\/"},{"@type":"ListItem","position":2,"name":"Pol\u00edtica de privacidad"}]},{"@type":"WebSite","@id":"https:\/\/edorteam.com\/en\/#website","url":"https:\/\/edorteam.com\/en\/","name":"Consultor\u00eda Compliance y protecci\u00f3n de datos","description":"Empresa de Ciberseguridad y Protecci\u00f3n de Datos","publisher":{"@id":"https:\/\/edorteam.com\/en\/#organization"},"alternateName":"Edorteam","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edorteam.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/edorteam.com\/en\/#organization","name":"Edorteam | Cibersecurity services and data protection company","alternateName":"Edorteam","url":"https:\/\/edorteam.com\/en\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/edorteam.com\/en\/#\/schema\/logo\/image\/","url":"https:\/\/edorteam.com\/wp-content\/uploads\/cropped-favicon.png","contentUrl":"https:\/\/edorteam.com\/wp-content\/uploads\/cropped-favicon.png","width":512,"height":512,"caption":"Edorteam | Cibersecurity services and data protection company"},"image":{"@id":"https:\/\/edorteam.com\/en\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/edorteam\/","https:\/\/x.com\/edorteam","https:\/\/www.linkedin.com\/company\/edorteam\/","https:\/\/www.instagram.com\/edorteam\/"]}]}},"_links":{"self":[{"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/pages\/19580","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/comments?post=19580"}],"version-history":[{"count":1,"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/pages\/19580\/revisions"}],"predecessor-version":[{"id":19589,"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/pages\/19580\/revisions\/19589"}],"wp:attachment":[{"href":"https:\/\/edorteam.com\/en\/wp-json\/wp\/v2\/media?parent=19580"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}