{"id":7934,"date":"2021-09-03T11:46:47","date_gmt":"2021-09-03T09:46:47","guid":{"rendered":"https:\/\/edorteam.com\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/"},"modified":"2021-09-24T12:57:52","modified_gmt":"2021-09-24T10:57:52","slug":"15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021","status":"publish","type":"post","link":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/","title":{"rendered":"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021"},"content":{"rendered":"<p>[et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.10.4&#8243; custom_padding=&#8221;||||true|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.8.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;0px|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;3.27.4&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p><strong>Hem analitzat i resumit les principals novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\/2021 que trasllada a la normativa espanyola la Directiva 2018\/843, coneguda com a Cinquena Directiva.<\/strong><\/p>\n<p>&nbsp;<\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_82_2 ez-toc-wrap-left-text counter-hierarchy ez-toc-counter ez-toc-custom ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title ez-toc-toggle\" style=\"cursor:pointer\">Contenido del art\u00edculo<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Toggle Table of Content\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Toggle<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #000000;color:#000000\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewBox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #000000;color:#000000\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewBox=\"0 0 24 24\" version=\"1.2\" baseProfile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1 ' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Novetats_LPBC_que_introdueix_lRD_72021\" >Novetats LPBC que introdueix l&#8217;RD 7\/2021<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-2\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Reforma_trascendental_en_materia_didentificacio_de_titularitats_reals\" >Reforma trascendental en mat\u00e8ria d&#8217;identificaci\u00f3 de titularitats reals<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-3\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Reconeixement_de_noves_tecnologies_en_lambit_de_la_PBC_en_relacio_amb_nous_subjectes_obligats\" >Reconeixement de noves tecnologies en l&#8217;\u00e0mbit de la PBC en relaci\u00f3 amb nous subjectes obligats<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-4\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Consultoria_LPBC_per_a_la_teva_empresa\" >Consultoria LPBC per a la teva empresa<\/a><ul class='ez-toc-list-level-4' ><li class='ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-5\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Ampliacio_de_subjectes_obligats_ja_existents\" >Ampliaci\u00f3 de subjectes obligats ja existents<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-6\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Noves_persones_amb_responsabilitat_publica\" >Noves persones amb responsabilitat p\u00fablica<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-7\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Diners_en_efectiu\" >Diners en efectiu<\/a><\/li><li class='ez-toc-page-1 ez-toc-heading-level-4'><a class=\"ez-toc-link ez-toc-heading-8\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#La_relacio_de_la_prevencio_del_Blanqueig_i_la_Proteccio_de_dades\" >La relaci\u00f3 de la prevenci\u00f3 del Blanqueig i la Protecci\u00f3 de dades<\/a><\/li><\/ul><\/li><li class='ez-toc-page-1 ez-toc-heading-level-3'><a class=\"ez-toc-link ez-toc-heading-9\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#Adapta_la_teva_empresa_a_lRGPD\" >Adapta la teva empresa a l&#8217;RGPD<\/a><\/li><\/ul><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"Novetats_LPBC_que_introdueix_lRD_72021\"><\/span>Novetats LPBC que introdueix l&#8217;RD 7\/2021<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<h4><span class=\"ez-toc-section\" id=\"Reforma_trascendental_en_materia_didentificacio_de_titularitats_reals\"><\/span>Reforma trascendental en mat\u00e8ria d&#8217;identificaci\u00f3 de titularitats reals<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>1: Es crea el Registre General de Titularitats Reals<\/strong>, un sistema registral \u00fanic d&#8217;acc\u00e9s p\u00fablic que dep\u00e8n del Ministeri de Just\u00edcia.<br \/>Aquest registre garanteix la interconnexi\u00f3 amb la resta de registres de la UE i centralitza la informaci\u00f3 continguda als registres i bases de dades existents al Consell General del Notariat, el Registre Mercantil, els Registres de Fundaci\u00f3 i Associacions, entre d&#8217;altres.<br \/>Aix\u00f2 sense perjudici que els subjectes obligats, a la vegada hagin de fer les seves pr\u00f2pies comprovacions en mat\u00e8ria de transpar\u00e8ncia i titularitat.<\/li>\n<li><strong>2:<\/strong> S&#8217;estableix l&#8217;<strong>obligaci\u00f3<\/strong> per a les persones jur\u00eddiques i entitats sense personalitat jur\u00eddica d&#8217; <strong>obtenir, conservar (10 anys) y actualitzar aquesta informaci\u00f3 de titularitat real<\/strong> i proveir-la a autoritats i subjectes obligats.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Reconeixement_de_noves_tecnologies_en_lambit_de_la_PBC_en_relacio_amb_nous_subjectes_obligats\"><\/span>Reconeixement de noves tecnologies en l&#8217;\u00e0mbit de la PBC en relaci\u00f3 amb nous subjectes obligats<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>3: Son nous subjectes obligats els serveis de canvi de moneda virtual per moneda de curs legal.<\/strong> Serveis d&#8217;Ex-Change en crypto-actius i serveis de Waller de monedes que proporcionen una clau de cust\u00f2dia de monedes.<\/li>\n<li><strong>4: Tamb\u00e9 ho son els prove\u00efdors de serveis de cust\u00f2dia de moneders electr\u00f2nics,<\/strong>entenent com a tals aquelles persones f\u00edsiques o jur\u00eddiques que donen serveis de cust\u00f2dia de claus criptogr\u00e0fiques privades en nom dels seus clients.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.9.2&#8243; background_color=&#8221;#0073ce&#8221; custom_padding=&#8221;0px||0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_duration=&#8221;800ms&#8221; animation_intensity_slide=&#8221;5%&#8221; global_module=&#8221;7922&#8243; saved_tabs=&#8221;all&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.10.4&#8243; background_color=&#8221;#ffffff&#8221; width=&#8221;90%&#8221; max_width=&#8221;1800px&#8221; custom_margin=&#8221;0px||0px&#8221; custom_padding=&#8221;0px||0px|&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.10.4&#8243; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#0073ce&#8221; header_2_font_size=&#8221;1.6em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;12%|8%|12%|8%|true|true&#8221; header_font_size_phone=&#8221;34px&#8221; header_font_size_last_edited=&#8221;off|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Consultoria_LPBC_per_a_la_teva_empresa\"><\/span>Consultoria LPBC per a la teva empresa<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>Compta amb Edorteam per a <strong>complir amb la Llei de Prevenci\u00f3 de Blanqueig de Capitals<\/strong> de forma \u00e0gil i efica\u00e7.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwOTAifX0=@&#8221; button_text=&#8221;T&#8217;ajudem&#8221; button_alignment=&#8221;right&#8221; _builder_version=&#8221;4.10.4&#8243; _dynamic_attributes=&#8221;button_url&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.10.4&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; background_image=&#8221;https:\/\/edorteam.com\/wp-content\/uploads\/evitar-fuga-de-informacion.jpg&#8221; custom_padding=&#8221;|||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwOTAifX0=@&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; background__hover_enabled=&#8221;on|hover&#8221; use_background_color_gradient__hover=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;rgba(0,70,140,0.75)&#8221; background_color_gradient_end__hover=&#8221;rgba(0,115,206,0.75)&#8221; background_color_gradient_overlays_image__hover=&#8221;on&#8221; background_blend__hover=&#8221;multiply&#8221; background_color__hover=&#8221;rgba(0,115,206,0.5)&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.8.1&#8243; height=&#8221;250px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.10.4&#8243; custom_margin=&#8221;50px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.8.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;0px|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text admin_label=&#8221;Text&#8221; _builder_version=&#8221;4.10.6&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Ampliacio_de_subjectes_obligats_ja_existents\"><\/span>Ampliaci\u00f3 de subjectes obligats ja existents<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>5:<\/strong> S&#8217;inclouen les <strong>persones f\u00edsiques i jur\u00eddiques a les que es refereixen els articles 14 i 15 del Reial Decret-llei 19\/2018<\/strong>, de serveis de pagament i altres mesures urgents en mat\u00e8ria financera.<\/li>\n<li><strong>6: Agents immobiliaris<\/strong> que actuen com a intermediaris en arrendament de b\u00e9ns immobles, \u00e9s a dir, ja no solament en accions de compra\/venda, sin\u00f3 tamb\u00e9 de lloguer. Aix\u00f2 s\u00ed, sempre i quan la quantitat de l&#8217;arrendament sigui igual o superior a 10.000 \u20ac\/mes o 120.000 \u20ac\/any.<\/li>\n<li><strong>7: &#8220;Els auditors de comptes, comptables externs, assessors ficals i qualsevol altra persona<\/strong>que es comprometi a oferir de manera directa o mitjan\u00e7ant altres persones relacionades, ajuda material, assist\u00e8ncia o assessorament en q\u00fcestions fiscals com activitat professional o empresarial principal&#8221;.<\/li>\n<li><strong>8: Intermediaris en el comer\u00e7 d&#8217;art i antiguitats<\/strong> i les persones que comercien o emmagatzemen aquests objectes.<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"Noves_persones_amb_responsabilitat_publica\"><\/span>Noves persones amb responsabilitat p\u00fablica<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<ul>\n<li><strong>9: C\u00e0rrecs d&#8217;alta direcci\u00f3 de partits pol\u00edtics<\/strong> amb representaci\u00f3 auton\u00f2mica, de municipis de capitals de prov\u00edncia o entitats locals de m\u00e9s de 50.000 habitants.<\/li>\n<li><strong>10: Persones que duen a terme funcions p\u00fabliques<\/strong> importants en el si d&#8217;organitzacions internacionals acreditades a l&#8217;estat.<\/li>\n<\/ul>\n<p><strong> <\/strong><\/p>\n<h4><span class=\"ez-toc-section\" id=\"Diners_en_efectiu\"><\/span>Diners en efectiu<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>Des del 3 de juny de 2021, resulta d&#8217;aplicaci\u00f3 el Reglament 2018\/1672 que substitueix l&#8217;anterior de 2005 i que regula els controls d&#8217;entrada i sortida d&#8217;efectiu en fronteres i territori nacionals (art. 34):<\/p>\n<ul>\n<li><strong>11: S&#8217;amplia la definici\u00f3<\/strong> d&#8217;all\u00f2 que s&#8217;ent\u00e8n per efectiu (incloent mat\u00e8ries primeres com l&#8217;or).<\/li>\n<li><strong>12: S&#8217;estableix un m\u00e0xim de 10.000 \u20ac d&#8217;entrada i sortida<\/strong> al territori nacional i de 100.000 \u20ac en moviments.<\/li>\n<li><strong>13: Canvi en la limitaci\u00f3 a la intervenci\u00f3 temporal<\/strong> de 30 a 90 dies. Amb la possibilitat d&#8217;interposar una reclamaci\u00f3 administrativa (art. 61 Llei i 7 del Reglament).<\/li>\n<\/ul>\n<p>&nbsp;<\/p>\n<h4><span class=\"ez-toc-section\" id=\"La_relacio_de_la_prevencio_del_Blanqueig_i_la_Proteccio_de_dades\"><\/span>La relaci\u00f3 de la prevenci\u00f3 del Blanqueig i la Protecci\u00f3 de dades<span class=\"ez-toc-section-end\"><\/span><\/h4>\n<p>S&#8217;estableix un nou Article 32 bis el qual remet a l&#8217;article 8.1 de la Llei Org\u00e0nica 3\/2018:<\/p>\n<ul>\n<li><strong>14:<\/strong> Obligaci\u00f3 dels subjectes obligats de realitzar una <strong>evaluaci\u00f3 d&#8217;impacte en la protecci\u00f3 de dades<\/strong> dels tractaments.<\/li>\n<li><strong>15:<\/strong> Prohibici\u00f3 d&#8217;utilitzaci\u00f3 de les dades obtingudes <strong>per a finalitats diferents<\/strong> de les relacionades amb la Prevenci\u00f3 del Blanqueig sense consentiment previ.<\/li>\n<\/ul>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; _builder_version=&#8221;4.8.1&#8243; background_color=&#8221;#0073ce&#8221; custom_padding=&#8221;0px||0px&#8221; animation_style=&#8221;slide&#8221; animation_direction=&#8221;bottom&#8221; animation_duration=&#8221;800ms&#8221; animation_intensity_slide=&#8221;5%&#8221; global_module=&#8221;4101&#8243; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row column_structure=&#8221;1_2,1_2&#8243; use_custom_gutter=&#8221;on&#8221; gutter_width=&#8221;1&#8243; make_equal=&#8221;on&#8221; _builder_version=&#8221;4.8.1&#8243; background_color=&#8221;#ffffff&#8221; width=&#8221;90%&#8221; max_width=&#8221;1800px&#8221; custom_margin=&#8221;0px||0px&#8221; custom_padding=&#8221;0px||0px|&#8221; use_custom_width=&#8221;on&#8221; width_unit=&#8221;off&#8221; custom_width_percent=&#8221;90%&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.8.1&#8243; header_2_font=&#8221;|700|||||||&#8221; header_2_text_color=&#8221;#0073ce&#8221; header_2_font_size=&#8221;1.6em&#8221; custom_margin=&#8221;||0px||false|false&#8221; custom_padding=&#8221;12%|8%|12%|8%|true|true&#8221; header_font_size_phone=&#8221;34px&#8221; header_font_size_last_edited=&#8221;off|phone&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<h3><span class=\"ez-toc-section\" id=\"Adapta_la_teva_empresa_a_lRGPD\"><\/span>Adapta la teva empresa a l&#8217;RGPD<span class=\"ez-toc-section-end\"><\/span><\/h3>\n<p>En vigor des de 2018, afecta a totes les empreses de la Uni\u00f3 Europea. Tot i que a l&#8217;estat ja exist\u00eds la LOPD, l&#8217;RGPD introdueix nova normativa i, per tant, s&#8217;han d&#8217;aplicar canvis.<\/p>\n<p>[\/et_pb_text][et_pb_button button_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMDcifX0=@&#8221; button_text=&#8221;T&#8217;ajudem&#8221; button_alignment=&#8221;right&#8221; _builder_version=&#8221;4.8.1&#8243; _dynamic_attributes=&#8221;button_url&#8221; background_layout=&#8221;dark&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_button][\/et_pb_column][et_pb_column type=&#8221;1_2&#8243; _builder_version=&#8221;4.8.1&#8243; _dynamic_attributes=&#8221;link_option_url&#8221; background_image=&#8221;https:\/\/edorteam.com\/wp-content\/uploads\/adecuacion-norma-rgpd-empresa.jpg&#8221; custom_padding=&#8221;|||&#8221; link_option_url=&#8221;@ET-DC@eyJkeW5hbWljIjp0cnVlLCJjb250ZW50IjoicG9zdF9saW5rX3VybF9wYWdlIiwic2V0dGluZ3MiOnsicG9zdF9pZCI6IjIwMDcifX0=@&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221; background__hover_enabled=&#8221;on|hover&#8221; use_background_color_gradient__hover=&#8221;off&#8221; background_color_gradient_start__hover=&#8221;rgba(0,70,140,0.75)&#8221; background_color_gradient_end__hover=&#8221;rgba(0,115,206,0.75)&#8221; background_color_gradient_overlays_image__hover=&#8221;on&#8221; background_blend__hover=&#8221;multiply&#8221; background_color__hover=&#8221;rgba(0,115,206,0.5)&#8221; background_enable_color__hover=&#8221;on&#8221;][et_pb_divider show_divider=&#8221;off&#8221; _builder_version=&#8221;4.8.1&#8243; height=&#8221;250px&#8221; global_colors_info=&#8221;{}&#8221;][\/et_pb_divider][\/et_pb_column][\/et_pb_row][\/et_pb_section][et_pb_section fb_built=&#8221;1&#8243; admin_label=&#8221;section&#8221; _builder_version=&#8221;4.10.4&#8243; custom_margin=&#8221;50px||||false|false&#8221; custom_padding=&#8221;||||false|false&#8221; locked=&#8221;off&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_row admin_label=&#8221;row&#8221; _builder_version=&#8221;4.8.1&#8243; background_size=&#8221;initial&#8221; background_position=&#8221;top_left&#8221; background_repeat=&#8221;repeat&#8221; width=&#8221;100%&#8221; custom_padding=&#8221;0px|0px||0px|false|false&#8221; global_colors_info=&#8221;{}&#8221;][et_pb_column type=&#8221;4_4&#8243; _builder_version=&#8221;3.25&#8243; custom_padding=&#8221;|||&#8221; global_colors_info=&#8221;{}&#8221; custom_padding__hover=&#8221;|||&#8221;][et_pb_text _builder_version=&#8221;4.10.4&#8243; _module_preset=&#8221;default&#8221; global_colors_info=&#8221;{}&#8221;]<\/p>\n<p>A Edorteam, treballem per a que la teva empresa estigui sempre al dia de les seves obligacions legals, tamb\u00e9 amb l&#8217;entrada en vigor de nova normativa.<\/p>\n<p>Si ets una <strong>empresa afectada per la LPBC<\/strong> o, amb l&#8217;entrada en vigor de l&#8217;RD 7\/2021, creus que t&#8217;afecta alguna d&#8217;aquestes novetats, <strong><a href=\"#contacto\">deixa-ho a les nostres mans i despreocupa&#8217;t<\/a><\/strong><\/p>\n<p>[\/et_pb_text][\/et_pb_column][\/et_pb_row][\/et_pb_section]<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hem analitzat i resumit les principals novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\/2021 que trasllada a la normativa espanyola la Directiva 2018\/843, coneguda com a Cinquena Directiva. &nbsp; Novetats LPBC que introdueix l&#8217;RD 7\/2021 Reforma trascendental en mat\u00e8ria d&#8217;identificaci\u00f3 de titularitats reals 1: Es [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":5691,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_et_pb_use_builder":"on","_et_pb_old_content":"","_et_gb_content_width":"","footnotes":""},"categories":[154,215],"tags":[219,214,146,218,218,156,156,216,193,139,217,149],"class_list":{"0":"post-7934","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","6":"hentry","7":"category-consultoria-juridica-ca","8":"category-prevencio-de-blanqueig-de-capitals","9":"tag-blanqueig-de-diners","10":"tag-compliment-normatiu","11":"tag-confidencialitat-de-les-dades","12":"tag-cryptomoneda-ca","14":"tag-etica-empresarial-ca","16":"tag-evaluacio-dimpacte","17":"tag-prevencio-de-riscos-penals","18":"tag-proteccio-de-dades","19":"tag-registre-general-de-titularitats-reals","20":"tag-tecnologies-de-la-informacio"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.5 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>15 novetats de l&#039;RD 7\/2021 en Prevenci\u00f3 de Blanqueig de Capitals<\/title>\n<meta name=\"description\" content=\"Analitzem les novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\/2021.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/\" \/>\n<meta property=\"og:locale\" content=\"ca_ES\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021\" \/>\n<meta property=\"og:description\" content=\"Novetats LPBC que introdueix l&#039;RD 7\/2021, una reforma trascendental en mat\u00e8ria d&#039;identificaci\u00f3 de titularitats reals i altres apartats\" \/>\n<meta property=\"og:url\" content=\"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/\" \/>\n<meta property=\"og:site_name\" content=\"Edorteam\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/edorteam\/\" \/>\n<meta property=\"article:published_time\" content=\"2021-09-03T09:46:47+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-09-24T10:57:52+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg\" \/>\n<meta name=\"author\" content=\"Edorteam\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:title\" content=\"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021\" \/>\n<meta name=\"twitter:description\" content=\"Novetats LPBC que introdueix l&#039;RD 7\/2021, una reforma trascendental en mat\u00e8ria d&#039;identificaci\u00f3 de titularitats reals i altres apartats\" \/>\n<meta name=\"twitter:image\" content=\"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg\" \/>\n<meta name=\"twitter:creator\" content=\"@edorteam\" \/>\n<meta name=\"twitter:site\" content=\"@edorteam\" \/>\n<meta name=\"twitter:label1\" content=\"Escrit per\" \/>\n\t<meta name=\"twitter:data1\" content=\"Edorteam\" \/>\n\t<meta name=\"twitter:label2\" content=\"Temps estimat de lectura\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minuts\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/\"},\"author\":{\"name\":\"Edorteam\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#\\\/schema\\\/person\\\/8d561d676383bddf2086b1de4aec37b6\"},\"headline\":\"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\\\/2021\",\"datePublished\":\"2021-09-03T09:46:47+00:00\",\"dateModified\":\"2021-09-24T10:57:52+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/\"},\"wordCount\":1662,\"commentCount\":12,\"publisher\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#organization\"},\"image\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/ley-blanqueo-capitales-lpbc-software.jpg\",\"keywords\":[\"blanqueig de diners\",\"compliment normatiu\",\"confidencialitat de les dades\",\"cryptomoneda\",\"cryptomoneda\",\"\u00e8tica empresarial\",\"\u00e8tica empresarial\",\"evaluaci\u00f3 d'impacte\",\"prevenci\u00f3 de riscos penals\",\"protecci\u00f3 de dades\",\"registre general de titularitats reals\",\"tecnologies de la informaci\u00f3\"],\"articleSection\":[\"Consultoria jur\u00eddica\",\"Prevenci\u00f3 de Blanqueig de Capitals\"],\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/\",\"url\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/\",\"name\":\"15 novetats de l'RD 7\\\/2021 en Prevenci\u00f3 de Blanqueig de Capitals\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/ley-blanqueo-capitales-lpbc-software.jpg\",\"datePublished\":\"2021-09-03T09:46:47+00:00\",\"dateModified\":\"2021-09-24T10:57:52+00:00\",\"description\":\"Analitzem les novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\\\/2021.\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#breadcrumb\"},\"inLanguage\":\"ca\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#primaryimage\",\"url\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/ley-blanqueo-capitales-lpbc-software.jpg\",\"contentUrl\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/ley-blanqueo-capitales-lpbc-software.jpg\",\"width\":509,\"height\":339,\"caption\":\"Prevenci\u00f3 de Blanqueig de Capitals\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\\\/2021\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#website\",\"url\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/\",\"name\":\"Consultor\u00eda Compliance y protecci\u00f3n de datos\",\"description\":\"Empresa de Ciberseguridad y Protecci\u00f3n de Datos\",\"publisher\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#organization\"},\"alternateName\":\"Edorteam\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"ca\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#organization\",\"name\":\"Edorteam | Empresa de ciberseguretat i protecci\u00f3 de dades\",\"alternateName\":\"Edorteam\",\"url\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"contentUrl\":\"https:\\\/\\\/edorteam.com\\\/wp-content\\\/uploads\\\/cropped-favicon.png\",\"width\":512,\"height\":512,\"caption\":\"Edorteam | Empresa de ciberseguretat i protecci\u00f3 de dades\"},\"image\":{\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/edorteam\\\/\",\"https:\\\/\\\/x.com\\\/edorteam\",\"https:\\\/\\\/www.linkedin.com\\\/company\\\/edorteam\\\/\",\"https:\\\/\\\/www.instagram.com\\\/edorteam\\\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/#\\\/schema\\\/person\\\/8d561d676383bddf2086b1de4aec37b6\",\"name\":\"Edorteam\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"ca\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g\",\"caption\":\"Edorteam\"},\"sameAs\":[\"http:\\\/\\\/edorteam.com\"],\"url\":\"https:\\\/\\\/edorteam.com\\\/ca\\\/author\\\/web_edorteam\\\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"15 novetats de l'RD 7\/2021 en Prevenci\u00f3 de Blanqueig de Capitals","description":"Analitzem les novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\/2021.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/","og_locale":"ca_ES","og_type":"article","og_title":"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021","og_description":"Novetats LPBC que introdueix l'RD 7\/2021, una reforma trascendental en mat\u00e8ria d'identificaci\u00f3 de titularitats reals i altres apartats","og_url":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/","og_site_name":"Edorteam","article_publisher":"https:\/\/www.facebook.com\/edorteam\/","article_published_time":"2021-09-03T09:46:47+00:00","article_modified_time":"2021-09-24T10:57:52+00:00","og_image":[{"url":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","type":"","width":"","height":""}],"author":"Edorteam","twitter_card":"summary_large_image","twitter_title":"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021","twitter_description":"Novetats LPBC que introdueix l'RD 7\/2021, una reforma trascendental en mat\u00e8ria d'identificaci\u00f3 de titularitats reals i altres apartats","twitter_image":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","twitter_creator":"@edorteam","twitter_site":"@edorteam","twitter_misc":{"Escrit per":"Edorteam","Temps estimat de lectura":"8 minuts"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#article","isPartOf":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/"},"author":{"name":"Edorteam","@id":"https:\/\/edorteam.com\/ca\/#\/schema\/person\/8d561d676383bddf2086b1de4aec37b6"},"headline":"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021","datePublished":"2021-09-03T09:46:47+00:00","dateModified":"2021-09-24T10:57:52+00:00","mainEntityOfPage":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/"},"wordCount":1662,"commentCount":12,"publisher":{"@id":"https:\/\/edorteam.com\/ca\/#organization"},"image":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","keywords":["blanqueig de diners","compliment normatiu","confidencialitat de les dades","cryptomoneda","cryptomoneda","\u00e8tica empresarial","\u00e8tica empresarial","evaluaci\u00f3 d'impacte","prevenci\u00f3 de riscos penals","protecci\u00f3 de dades","registre general de titularitats reals","tecnologies de la informaci\u00f3"],"articleSection":["Consultoria jur\u00eddica","Prevenci\u00f3 de Blanqueig de Capitals"],"inLanguage":"ca","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#respond"]}]},{"@type":"WebPage","@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/","url":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/","name":"15 novetats de l'RD 7\/2021 en Prevenci\u00f3 de Blanqueig de Capitals","isPartOf":{"@id":"https:\/\/edorteam.com\/ca\/#website"},"primaryImageOfPage":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#primaryimage"},"image":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#primaryimage"},"thumbnailUrl":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","datePublished":"2021-09-03T09:46:47+00:00","dateModified":"2021-09-24T10:57:52+00:00","description":"Analitzem les novetats en mat\u00e8ria de Prevenci\u00f3 de Blanqueig de Capitals (LPBC) que ha introdu\u00eft recentment el Reial Decret-llei 7\/2021.","breadcrumb":{"@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#breadcrumb"},"inLanguage":"ca","potentialAction":[{"@type":"ReadAction","target":["https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/"]}]},{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#primaryimage","url":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","contentUrl":"https:\/\/edorteam.com\/wp-content\/uploads\/ley-blanqueo-capitales-lpbc-software.jpg","width":509,"height":339,"caption":"Prevenci\u00f3 de Blanqueig de Capitals"},{"@type":"BreadcrumbList","@id":"https:\/\/edorteam.com\/ca\/15-novetats-en-prevencio-de-blanqueig-de-capitals-pel-reial-decret-llei-7-2021\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/edorteam.com\/ca\/"},{"@type":"ListItem","position":2,"name":"15 novetats en Prevenci\u00f3 de Blanqueig de Capitals pel Reial Decret-llei 7\/2021"}]},{"@type":"WebSite","@id":"https:\/\/edorteam.com\/ca\/#website","url":"https:\/\/edorteam.com\/ca\/","name":"Consultor\u00eda Compliance y protecci\u00f3n de datos","description":"Empresa de Ciberseguridad y Protecci\u00f3n de Datos","publisher":{"@id":"https:\/\/edorteam.com\/ca\/#organization"},"alternateName":"Edorteam","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/edorteam.com\/ca\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"ca"},{"@type":"Organization","@id":"https:\/\/edorteam.com\/ca\/#organization","name":"Edorteam | Empresa de ciberseguretat i protecci\u00f3 de dades","alternateName":"Edorteam","url":"https:\/\/edorteam.com\/ca\/","logo":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/edorteam.com\/ca\/#\/schema\/logo\/image\/","url":"https:\/\/edorteam.com\/wp-content\/uploads\/cropped-favicon.png","contentUrl":"https:\/\/edorteam.com\/wp-content\/uploads\/cropped-favicon.png","width":512,"height":512,"caption":"Edorteam | Empresa de ciberseguretat i protecci\u00f3 de dades"},"image":{"@id":"https:\/\/edorteam.com\/ca\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/edorteam\/","https:\/\/x.com\/edorteam","https:\/\/www.linkedin.com\/company\/edorteam\/","https:\/\/www.instagram.com\/edorteam\/"]},{"@type":"Person","@id":"https:\/\/edorteam.com\/ca\/#\/schema\/person\/8d561d676383bddf2086b1de4aec37b6","name":"Edorteam","image":{"@type":"ImageObject","inLanguage":"ca","@id":"https:\/\/secure.gravatar.com\/avatar\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/2e28be36471774aba19e1b15aa24a52aa2d8955a536897526f71cec2370a0a24?s=96&d=blank&r=g","caption":"Edorteam"},"sameAs":["http:\/\/edorteam.com"],"url":"https:\/\/edorteam.com\/ca\/author\/web_edorteam\/"}]}},"_links":{"self":[{"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/posts\/7934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/comments?post=7934"}],"version-history":[{"count":0,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/posts\/7934\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/media\/5691"}],"wp:attachment":[{"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/media?parent=7934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/categories?post=7934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/edorteam.com\/ca\/wp-json\/wp\/v2\/tags?post=7934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}